{"id":453,"date":"2024-01-16T10:56:07","date_gmt":"2024-01-16T09:56:07","guid":{"rendered":"http:\/\/www.chroniquesaubieroises.fr\/?p=453"},"modified":"2025-12-06T09:31:26","modified_gmt":"2025-12-06T08:31:26","slug":"le-rampeau-a-aubiere","status":"publish","type":"post","link":"https:\/\/www.chroniquesaubieroises.fr\/index.php\/2024\/01\/16\/le-rampeau-a-aubiere\/","title":{"rendered":"Le rampeau \u00e0 Aubi\u00e8re"},"content":{"rendered":"\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"http:\/\/www.chroniquesaubieroises.fr\/wp-content\/uploads\/2024\/03\/Jeu-de-rampeau-a-Aubiere-en-1653_2024-2-0.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Contenu embarqu\u00e9 Jeu-de-rampeau-a-Aubiere-en-1653_2024-2-0.\"><\/object><a id=\"wp-block-file--media-da47d25c-03af-4831-85ea-30ea66234fb6\" href=\"http:\/\/www.chroniquesaubieroises.fr\/wp-content\/uploads\/2024\/03\/Jeu-de-rampeau-a-Aubiere-en-1653_2024-2-0.pdf\">Jeu-de-rampeau-a-Aubiere-en-1653_2024-2-0<\/a><a href=\"http:\/\/www.chroniquesaubieroises.fr\/wp-content\/uploads\/2024\/03\/Jeu-de-rampeau-a-Aubiere-en-1653_2024-2-0.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-da47d25c-03af-4831-85ea-30ea66234fb6\">T\u00e9l\u00e9charger<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Peut-on imaginer Gilberte de La Rochebriant de Chovance, cette Dame d\u2019Aubi\u00e8re si appr\u00e9ci\u00e9e de ses sujets aubi\u00e9rois, qu\u2019elle puisse tirer profit d\u2019une de leurs rares distractions ?<br \/>\nC\u2019est pourtant ce que nous apprend un acte notari\u00e9 de 1677, intitul\u00e9 : \u00ab D\u00e9partement du jeu de quilles de Blaize et Jacques Recollene, p\u00e8re et fils, au proffict de Madame d\u2019Aubi\u00e8re \u00bb\u2026<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[4,7],"tags":[18,86,37],"class_list":["post-453","post","type-post","status-publish","format-standard","hentry","category-chroniques","category-chroniques-judiciaires","tag-aubiere","tag-jeu-de-rampeau","tag-justice"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.chroniquesaubieroises.fr\/index.php\/wp-json\/wp\/v2\/posts\/453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.chroniquesaubieroises.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chroniquesaubieroises.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chroniquesaubieroises.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chroniquesaubieroises.fr\/index.php\/wp-json\/wp\/v2\/comments?post=453"}],"version-history":[{"count":2,"href":"https:\/\/www.chroniquesaubieroises.fr\/index.php\/wp-json\/wp\/v2\/posts\/453\/revisions"}],"predecessor-version":[{"id":708,"href":"https:\/\/www.chroniquesaubieroises.fr\/index.php\/wp-json\/wp\/v2\/posts\/453\/revisions\/708"}],"wp:attachment":[{"href":"https:\/\/www.chroniquesaubieroises.fr\/index.php\/wp-json\/wp\/v2\/media?parent=453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chroniquesaubieroises.fr\/index.php\/wp-json\/wp\/v2\/categories?post=453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chroniquesaubieroises.fr\/index.php\/wp-json\/wp\/v2\/tags?post=453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}