{"id":1805,"date":"2026-04-30T10:51:17","date_gmt":"2026-04-30T08:51:17","guid":{"rendered":"https:\/\/www.chroniquesaubieroises.fr\/?p=1805"},"modified":"2026-04-30T10:51:18","modified_gmt":"2026-04-30T08:51:18","slug":"actes-divers-de-1632","status":"publish","type":"post","link":"https:\/\/www.chroniquesaubieroises.fr\/index.php\/2026\/04\/30\/actes-divers-de-1632\/","title":{"rendered":"Actes divers de 1632"},"content":{"rendered":"\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/www.chroniquesaubieroises.fr\/wp-content\/uploads\/2026\/04\/1632_Actes-divers.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Contenu embarqu\u00e9 1632_Actes divers.\"><\/object><a id=\"wp-block-file--media-c7768e88-c7a8-448c-a22c-4e9ad3c360f6\" href=\"https:\/\/www.chroniquesaubieroises.fr\/wp-content\/uploads\/2026\/04\/1632_Actes-divers.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">1632_Actes divers<\/a><a href=\"https:\/\/www.chroniquesaubieroises.fr\/wp-content\/uploads\/2026\/04\/1632_Actes-divers.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-c7768e88-c7a8-448c-a22c-4e9ad3c360f6\">T\u00e9l\u00e9charger<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Tous les actes \u00ab\u00a0divers\u00a0\u00bb de l&rsquo;ann\u00e9e 1632.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[139,9],"tags":[141,18,20],"class_list":["post-1805","post","type-post","status-publish","format-standard","hentry","category-actes-divers","category-archives-notariales","tag-actes-divers","tag-aubiere","tag-notaires"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.chroniquesaubieroises.fr\/index.php\/wp-json\/wp\/v2\/posts\/1805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.chroniquesaubieroises.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chroniquesaubieroises.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chroniquesaubieroises.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chroniquesaubieroises.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1805"}],"version-history":[{"count":1,"href":"https:\/\/www.chroniquesaubieroises.fr\/index.php\/wp-json\/wp\/v2\/posts\/1805\/revisions"}],"predecessor-version":[{"id":1807,"href":"https:\/\/www.chroniquesaubieroises.fr\/index.php\/wp-json\/wp\/v2\/posts\/1805\/revisions\/1807"}],"wp:attachment":[{"href":"https:\/\/www.chroniquesaubieroises.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chroniquesaubieroises.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chroniquesaubieroises.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}