{"id":147,"date":"2023-12-27T15:57:23","date_gmt":"2023-12-27T14:57:23","guid":{"rendered":"http:\/\/www.chroniquesaubieroises.fr\/?p=147"},"modified":"2024-01-07T15:28:17","modified_gmt":"2024-01-07T14:28:17","slug":"acquisitions-de-1586-a-1600","status":"publish","type":"post","link":"https:\/\/www.chroniquesaubieroises.fr\/index.php\/2023\/12\/27\/acquisitions-de-1586-a-1600\/","title":{"rendered":"Acquisitions de 1586 \u00e0 1600"},"content":{"rendered":"\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"http:\/\/www.chroniquesaubieroises.fr\/wp-content\/uploads\/2023\/12\/Acquisitions-de-1586-a-1600_2023-1.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Contenu embarqu\u00e9 Acquisitions-de-1586-a-1600_2023-1.\"><\/object><a id=\"wp-block-file--media-a4d15042-0b3f-4ec2-83a7-3bd5b905b261\" href=\"http:\/\/www.chroniquesaubieroises.fr\/wp-content\/uploads\/2023\/12\/Acquisitions-de-1586-a-1600_2023-1.pdf\">Acquisitions-de-1586-a-1600_2023-1<\/a><a href=\"http:\/\/www.chroniquesaubieroises.fr\/wp-content\/uploads\/2023\/12\/Acquisitions-de-1586-a-1600_2023-1.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-a4d15042-0b3f-4ec2-83a7-3bd5b905b261\">T\u00e9l\u00e9charger<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Vous trouverez ci-dessous l\u2019ensemble des acquisitions ou ventes qui ont \u00e9t\u00e9 pass\u00e9es par des Aubi\u00e9rois ou autres par devant ma\u00eetre Guillaume Aubeny, notaire royal \u00e0 Aubi\u00e8re, durant les ann\u00e9es 1586 \u00e0 1600.<br \/>\nLes textes ne sont pas toujours pr\u00e9sent\u00e9s dans leur transcription int\u00e9grale, mais l\u2019essentiel des faits, des donn\u00e9es et des personnes pr\u00e9sentes et\/ou concern\u00e9es par ces actes est soumis \u00e0 votre connaissance.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[9,59],"tags":[51,18,53,52],"class_list":["post-147","post","type-post","status-publish","format-standard","hentry","category-archives-notariales","category-ventes","tag-acquisitions","tag-aubiere","tag-notaire","tag-ventes"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.chroniquesaubieroises.fr\/index.php\/wp-json\/wp\/v2\/posts\/147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.chroniquesaubieroises.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chroniquesaubieroises.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chroniquesaubieroises.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chroniquesaubieroises.fr\/index.php\/wp-json\/wp\/v2\/comments?post=147"}],"version-history":[{"count":3,"href":"https:\/\/www.chroniquesaubieroises.fr\/index.php\/wp-json\/wp\/v2\/posts\/147\/revisions"}],"predecessor-version":[{"id":183,"href":"https:\/\/www.chroniquesaubieroises.fr\/index.php\/wp-json\/wp\/v2\/posts\/147\/revisions\/183"}],"wp:attachment":[{"href":"https:\/\/www.chroniquesaubieroises.fr\/index.php\/wp-json\/wp\/v2\/media?parent=147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chroniquesaubieroises.fr\/index.php\/wp-json\/wp\/v2\/categories?post=147"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chroniquesaubieroises.fr\/index.php\/wp-json\/wp\/v2\/tags?post=147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}